{"id":7902,"date":"2024-05-22T17:36:23","date_gmt":"2024-05-22T15:36:23","guid":{"rendered":"https:\/\/www.e-leclerc.es\/vitoria-gasteiz\/?page_id=7902"},"modified":"2024-06-14T10:40:14","modified_gmt":"2024-06-14T08:40:14","slug":"politica-de-proteccion-de-datos","status":"publish","type":"page","link":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/","title":{"rendered":"Compromiso con la Protecci\u00f3n de Datos Personales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7902\" class=\"elementor elementor-7902\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3da2821 e-flex e-con-boxed e-con e-parent\" data-id=\"3da2821\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d59de19 elementor-invisible elementor-widget elementor-widget-rt-title\" data-id=\"d59de19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-section-title style1\">\n\t<div class=\"title-holder\">\t\t\n\t\t\t\t\t\t<div class=\"heading-wrap \"><h2 class=\"entry-title hide fadeInUp\" data-wow-delay=\"0.4s\" data-wow-duration=\"1.2s\">COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES<\/h2><\/div>\n\t\t\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e17ea4 elementor-invisible elementor-widget elementor-widget-rt-title\" data-id=\"5e17ea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-section-title style1\">\n\t<div class=\"title-holder\">\t\t\n\t\t\t\t\t\t<div class=\"heading-wrap \"><h2 class=\"entry-title hide fadeInUp\" data-wow-delay=\"0.4s\" data-wow-duration=\"1.2s\">NUESTRO COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES: \u201cPERSONAS INFORMADAS Y DATOS PROTEGIDOS\u201d<\/h2><\/div>\n\t\t\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa32c52 elementor-widget elementor-widget-text-editor\" data-id=\"fa32c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Direcci\u00f3n \/ \u00d3rgano de Gobierno de <strong>VITORIADIS S.L.<\/strong> (en adelante, el responsable del tratamiento), asume la m\u00e1xima responsabilidad y compromiso con el establecimiento, implementaci\u00f3n y mantenimiento de la presente Pol\u00edtica de Protecci\u00f3n de Datos, garantizando la mejora continua del responsable del tratamiento con el objetivo de alcanzar la excelencia en relaci\u00f3n con el cumplimiento del Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos y por el que se deroga la Directiva 95\/46\/CE (Reglamento general de protecci\u00f3n de datos) (DOUE L 119\/1, 04-05-2016), y de la normativa espa\u00f1ola de protecci\u00f3n de datos de car\u00e1cter personal (Ley Org\u00e1nica, legislaci\u00f3n sectorial espec\u00edfica y sus normas de desarrollo).<\/p><p>La Pol\u00edtica de Protecci\u00f3n de Datos de <strong>VITORIADIS S.L.<\/strong> descansa en el <u>principio de responsabilidad proactiva<\/u>, seg\u00fan el cual el responsable del tratamiento es responsable del cumplimiento del marco normativo y jurisprudencial que gobierna dicha Pol\u00edtica, y es capaz de demostrarlo ante las autoridades de control competentes.<\/p><p>En tal sentido, el responsable del tratamiento se regir\u00e1 por los siguientes principios que deben servir a todo su personal como gu\u00eda y marco de referencia en el tratamiento de datos personales:<\/p><ol><li><u>Protecci\u00f3n de datos desde el dise\u00f1o:<\/u> el responsable del tratamiento aplicar\u00e1, tanto en el momento de determinar los medios de tratamiento como en el momento del propio tratamiento, medidas t\u00e9cnicas y organizativas apropiadas, como la seudonimizaci\u00f3n, concebidas para aplicar de forma efectiva los principios de protecci\u00f3n de datos, como la minimizaci\u00f3n de datos, e integrar las garant\u00edas necesarias en el tratamiento.<\/li><li><u>Protecci\u00f3n de datos por defecto:<\/u> el responsable del tratamiento aplicar\u00e1 las medidas t\u00e9cnicas y organizativas apropiadas con miras a garantizar que, por defecto, solo sean objeto de tratamiento los datos personales que sean necesarios para cada uno de los fines espec\u00edficos del tratamiento.<\/li><li><u>Protecci\u00f3n de datos en el ciclo de vida de la informaci\u00f3n:<\/u> las medidas que garanticen la protecci\u00f3n de los datos personales ser\u00e1n aplicables durante el ciclo completo de la vida de la informaci\u00f3n.<\/li><li><u>Licitud, lealtad y transparencia:<\/u> los datos personales ser\u00e1n tratados de manera l\u00edcita, leal y transparente en relaci\u00f3n con el interesado.<\/li><li><u>Limitaci\u00f3n de la finalidad:<\/u> los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos, y no ser\u00e1n tratados ulteriormente de manera incompatible con dichos fines.<\/li><li><u>Minimizaci\u00f3n de datos:<\/u> los datos personales ser\u00e1n adecuados, pertinentes y limitados a lo necesario en relaci\u00f3n con los fines para los que son tratados.<\/li><li><u>Exactitud:<\/u> los datos personales ser\u00e1n exactos y, si fuera necesario, actualizados; se adoptar\u00e1n todas las medidas razonables para que se supriman o rectifiquen sin dilaci\u00f3n los datos personales que sean inexactos con respecto a los fines para los que se tratan.<\/li><li><u>Limitaci\u00f3n del plazo de conservaci\u00f3n:<\/u> los datos personales ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n de los interesados durante no m\u00e1s tiempo del necesario para los fines del tratamiento de los datos personales.<\/li><li><u>Integridad y confidencialidad:<\/u> los datos personales ser\u00e1n tratados de tal manera que se garantice una seguridad adecuada de los datos personales, incluida la protecci\u00f3n contra el tratamiento no autorizado o il\u00edcito y contra su p\u00e9rdida, destrucci\u00f3n o da\u00f1o accidental, mediante la aplicaci\u00f3n de medidas t\u00e9cnicas u organizativas apropiadas.<\/li><li><u>Informaci\u00f3n y formaci\u00f3n:<\/u> una de las claves para garantizar la protecci\u00f3n de los datos personales es la formaci\u00f3n e informaci\u00f3n que se facilite al personal involucrado en el tratamiento de los mismos. Durante el ciclo de vida de la informaci\u00f3n, todo el personal con acceso a los datos ser\u00e1 convenientemente formado e informado acerca de sus obligaciones en relaci\u00f3n con el cumplimiento de la normativa de protecci\u00f3n de datos.<\/li><\/ol><p>La Pol\u00edtica de Protecci\u00f3n de Datos de <strong>VITORIADIS S.L. <\/strong>es comunicada a todo el personal del responsable del tratamiento y puesta a disposici\u00f3n de todas las partes interesadas.<\/p><p>En su consecuencia, la presente Pol\u00edtica de Protecci\u00f3n de Datos involucra a todo el personal del responsable del tratamiento, que debe conocerla y asumirla, consider\u00e1ndola como propia, siendo cada miembro responsable de aplicarla y de verificar las normas de protecci\u00f3n de datos aplicables a su actividad, as\u00ed como identificar y aportar las oportunidades de mejora que considere oportunas con el objetivo de alcanzar la excelencia en relaci\u00f3n con su cumplimiento.<\/p><p>Esta Pol\u00edtica ser\u00e1 revisada por la Direcci\u00f3n \/ \u00d3rgano de Gobierno de <strong>VITORIADIS S.L.<\/strong>, tantas veces como se considere necesario, para adecuarse, en todo momento, a las disposiciones vigentes en materia de protecci\u00f3n de datos de car\u00e1cter personal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES NUESTRO COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES: \u201cPERSONAS INFORMADAS Y DATOS PROTEGIDOS\u201d La Direcci\u00f3n \/ \u00d3rgano de Gobierno de VITORIADIS S.L. (en adelante, el responsable del tratamiento), asume la m\u00e1xima responsabilidad y compromiso con el establecimiento, implementaci\u00f3n y mantenimiento de la presente Pol\u00edtica de Protecci\u00f3n de Datos, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7902","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz\" \/>\n<meta property=\"og:description\" content=\"COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES NUESTRO COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES: \u201cPERSONAS INFORMADAS Y DATOS PROTEGIDOS\u201d La Direcci\u00f3n \/ \u00d3rgano de Gobierno de VITORIADIS S.L. (en adelante, el responsable del tratamiento), asume la m\u00e1xima responsabilidad y compromiso con el establecimiento, implementaci\u00f3n y mantenimiento de la presente Pol\u00edtica de Protecci\u00f3n de Datos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Vitoria-Gasteiz\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T08:40:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/politica-de-proteccion-de-datos\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/politica-de-proteccion-de-datos\\\/\",\"name\":\"Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#website\"},\"datePublished\":\"2024-05-22T15:36:23+00:00\",\"dateModified\":\"2024-06-14T08:40:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/politica-de-proteccion-de-datos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/politica-de-proteccion-de-datos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/politica-de-proteccion-de-datos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compromiso con la Protecci\u00f3n de Datos Personales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\",\"name\":\"E.Leclerc Vitoria-Gasteiz\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Vitoria-Gasteiz en Pa\u00eds Vasco. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#organization\",\"name\":\"E.Leclerc Vitoria-Gasteiz\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"caption\":\"E.Leclerc Vitoria-Gasteiz\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/","og_locale":"es_ES","og_type":"article","og_title":"Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz","og_description":"COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES NUESTRO COMPROMISO CON LA PROTECCI\u00d3N DE DATOS PERSONALES: \u201cPERSONAS INFORMADAS Y DATOS PROTEGIDOS\u201d La Direcci\u00f3n \/ \u00d3rgano de Gobierno de VITORIADIS S.L. (en adelante, el responsable del tratamiento), asume la m\u00e1xima responsabilidad y compromiso con el establecimiento, implementaci\u00f3n y mantenimiento de la presente Pol\u00edtica de Protecci\u00f3n de Datos, [&hellip;]","og_url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/","og_site_name":"E.Leclerc Vitoria-Gasteiz","article_modified_time":"2024-06-14T08:40:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/","name":"Compromiso con la Protecci\u00f3n de Datos Personales - E.Leclerc Vitoria-Gasteiz","isPartOf":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#website"},"datePublished":"2024-05-22T15:36:23+00:00","dateModified":"2024-06-14T08:40:14+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/politica-de-proteccion-de-datos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/"},{"@type":"ListItem","position":2,"name":"Compromiso con la Protecci\u00f3n de Datos Personales"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#website","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/","name":"E.Leclerc Vitoria-Gasteiz","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Vitoria-Gasteiz en Pa\u00eds Vasco. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#organization","name":"E.Leclerc Vitoria-Gasteiz","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/03\/Leclerc_Logo.svg","contentUrl":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/03\/Leclerc_Logo.svg","caption":"E.Leclerc Vitoria-Gasteiz"},"image":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/comments?post=7902"}],"version-history":[{"count":8,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7902\/revisions"}],"predecessor-version":[{"id":8083,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7902\/revisions\/8083"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/media?parent=7902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}