{"id":7703,"date":"2024-04-29T21:30:09","date_gmt":"2024-04-29T19:30:09","guid":{"rendered":"https:\/\/www.e-leclerc.es\/vitoria-gasteiz\/?page_id=7703"},"modified":"2025-02-07T09:48:29","modified_gmt":"2025-02-07T08:48:29","slug":"ventajas","status":"publish","type":"page","link":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/","title":{"rendered":"Ventajas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7703\" class=\"elementor elementor-7703\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf7659 e-flex e-con-boxed e-con e-parent\" data-id=\"eaf7659\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-752cbe4 e-con-full e-flex e-con e-child\" data-id=\"752cbe4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f4e79c7 e-con-full e-flex e-con e-child\" data-id=\"f4e79c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bbfe1e7 e-con-full e-flex e-con e-child\" data-id=\"bbfe1e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cbab0a elementor-widget elementor-widget-button\" data-id=\"1cbab0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inicio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1409df6 elementor-widget elementor-widget-button\" data-id=\"1409df6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#inicio\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ventajas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1098803 elementor-widget elementor-widget-button\" data-id=\"1098803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/solicitar-tarjeta\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar tarjeta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cfc023 elementor-widget elementor-widget-button\" data-id=\"1cfc023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/protege-tu-ahorro\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Protege tu ahorro<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c84ebd8 elementor-widget elementor-widget-button\" data-id=\"c84ebd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/preguntas-frecuentes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Preguntas frecuentes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9923e9e e-flex e-con-boxed e-con e-parent\" data-id=\"9923e9e\" data-element_type=\"container\" data-e-type=\"container\" id=\"inicio\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-79b7b8c8 e-con-full e-flex e-con e-child\" data-id=\"79b7b8c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e147992 elementor-invisible elementor-widget elementor-widget-rt-title-with-text\" data-id=\"5e147992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-title-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-title-text has-animation\">\n\t\t\t<div class=\"entry-subtitle hide fadeInUp\" data-wow-delay=\"0.2s\" data-wow-duration=\"1.2s\">Ticket E.Leclerc<\/div>\n\t\t\t\t<h2 class=\"entry-title hide fadeInUp\" data-wow-delay=\"0.4s\" data-wow-duration=\"1.2s\">La tarjeta E.Leclerc te permite acumular\nbonos de compra, llamados \u201ctickets\nE.Leclerc\u201d que puedes descontar del\nimporte de las compras, excepto\ncarburantes.<\/h2>\t\t\n\t\t\n\t<div class=\"entry-content hide fadeInUp\" data-wow-delay=\"0.6s\" data-wow-duration=\"1.2s\"><\/div>\n\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f3b3750 e-con-full e-flex e-con e-child\" data-id=\"1f3b3750\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36d24338 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"36d24338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-1.svg\" class=\"attachment-full size-full wp-image-3359\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f14e6eb e-flex e-con-boxed e-con e-parent\" data-id=\"2f14e6eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3497cd48 e-con-full e-flex e-con e-child\" data-id=\"3497cd48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-456a4e40 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"456a4e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-2.svg\" class=\"attachment-full size-full wp-image-3363\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e6367eb e-con-full e-flex e-con e-child\" data-id=\"7e6367eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-525cd4bd elementor-invisible elementor-widget elementor-widget-rt-title-with-text\" data-id=\"525cd4bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-title-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-title-text has-animation\">\n\t\t\t<div class=\"entry-subtitle hide fadeInUp\" data-wow-delay=\"0.2s\" data-wow-duration=\"1.2s\">Ticket E.Leclerc<\/div>\n\t\t\t\t<h2 class=\"entry-title hide fadeInUp\" data-wow-delay=\"0.4s\" data-wow-duration=\"1.2s\">Util\u00edzala en todas las tiendas E.Leclerc que\nparticipen en los programas de fidelidad\npara ahorrar en cada compra la pasar por\nla l\u00ednea de caja.<\/h2>\t\t\n\t\t\n\t<div class=\"entry-content hide fadeInUp\" data-wow-delay=\"0.6s\" data-wow-duration=\"1.2s\"><\/div>\n\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a0c8aae e-flex e-con-boxed e-con e-parent\" data-id=\"2a0c8aae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-55302455 e-con-full e-flex e-con e-child\" data-id=\"55302455\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c48c5f5 elementor-invisible elementor-widget elementor-widget-rt-title-with-text\" data-id=\"3c48c5f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-title-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-title-text has-animation\">\n\t\t\t<div class=\"entry-subtitle hide fadeInUp\" data-wow-delay=\"0.2s\" data-wow-duration=\"1.2s\">Ticket E.Leclerc<\/div>\n\t\t\t\t<h2 class=\"entry-title hide fadeInUp\" data-wow-delay=\"0.4s\" data-wow-duration=\"1.2s\">Las cuentas de varios titulares pueden\nadicionarse y utilizarse por el titular o por\nterceros, con el fin de acumular tickets\nE.Leclerc en la tarjeta principal.<\/h2>\t\t\n\t\t\n\t<div class=\"entry-content hide fadeInUp\" data-wow-delay=\"0.6s\" data-wow-duration=\"1.2s\"><\/div>\n\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a352203 e-con-full e-flex e-con e-child\" data-id=\"4a352203\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f16795d elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"1f16795d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-3.svg\" class=\"attachment-full size-full wp-image-3364\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a90fdb e-flex e-con-boxed e-con e-parent\" data-id=\"1a90fdb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f823596 e-flex e-con-boxed e-con e-child\" data-id=\"f823596\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c2f95b7 e-flex e-con-boxed e-con e-child\" data-id=\"c2f95b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-969d8ca elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"969d8ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"311\" height=\"326\" src=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/06\/frame-gasolineras.svg\" class=\"attachment-large size-large wp-image-8076\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9360e12 e-flex e-con-boxed e-con e-child\" data-id=\"9360e12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47f50c4 elementor-widget elementor-widget-heading\" data-id=\"47f50c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una tarjeta con la que AHORRAR \nEN LA COMPRA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca256b2 elementor-invisible elementor-widget elementor-widget-rt-button\" data-id=\"1ca256b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-button hide fadeInUp\" data-wow-delay=\"0.2s\" data-wow-duration=\"1.2s\">\n\t\t\t<a class=\"button-link button-style-4\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/solicitar-tarjeta\/\">\n                        <span class=\"button-text button-text-right\">Solicitar tarjeta<\/span>\n                        <span class=\"icon icon-right\"><i class=\" icon-zilly-right-arrow\"><\/i><\/span>                    <\/a>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21b8e7e e-flex e-con-boxed e-con e-child\" data-id=\"21b8e7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d266115 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"d266115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/06\/tarjeta-dinero.svg\" class=\"attachment-large size-large wp-image-8077\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inicio Ventajas Solicitar tarjeta Protege tu ahorro Preguntas frecuentes Ticket E.Leclerc La tarjeta E.Leclerc te permite acumular bonos de compra, llamados \u201ctickets E.Leclerc\u201d que puedes descontar del importe de las compras, excepto carburantes. Ticket E.Leclerc Util\u00edzala en todas las tiendas E.Leclerc que participen en los programas de fidelidad para ahorrar en cada compra la pasar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7690,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7703","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventajas - E.Leclerc Vitoria-Gasteiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventajas - E.Leclerc Vitoria-Gasteiz\" \/>\n<meta property=\"og:description\" content=\"Inicio Ventajas Solicitar tarjeta Protege tu ahorro Preguntas frecuentes Ticket E.Leclerc La tarjeta E.Leclerc te permite acumular bonos de compra, llamados \u201ctickets E.Leclerc\u201d que puedes descontar del importe de las compras, excepto carburantes. Ticket E.Leclerc Util\u00edzala en todas las tiendas E.Leclerc que participen en los programas de fidelidad para ahorrar en cada compra la pasar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Vitoria-Gasteiz\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T08:48:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/\",\"name\":\"Ventajas - E.Leclerc Vitoria-Gasteiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/04\\\/ventajas-1.svg\",\"datePublished\":\"2024-04-29T19:30:09+00:00\",\"dateModified\":\"2025-02-07T08:48:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/04\\\/ventajas-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/04\\\/ventajas-1.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/ventajas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tarjeta E.Leclerc\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/tarjeta-e-leclerc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ventajas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\",\"name\":\"E.Leclerc Vitoria-Gasteiz\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Vitoria-Gasteiz en Pa\u00eds Vasco. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#organization\",\"name\":\"E.Leclerc Vitoria-Gasteiz\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"caption\":\"E.Leclerc Vitoria-Gasteiz\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/vitoria-gasteiz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ventajas - E.Leclerc Vitoria-Gasteiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/","og_locale":"es_ES","og_type":"article","og_title":"Ventajas - E.Leclerc Vitoria-Gasteiz","og_description":"Inicio Ventajas Solicitar tarjeta Protege tu ahorro Preguntas frecuentes Ticket E.Leclerc La tarjeta E.Leclerc te permite acumular bonos de compra, llamados \u201ctickets E.Leclerc\u201d que puedes descontar del importe de las compras, excepto carburantes. Ticket E.Leclerc Util\u00edzala en todas las tiendas E.Leclerc que participen en los programas de fidelidad para ahorrar en cada compra la pasar [&hellip;]","og_url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/","og_site_name":"E.Leclerc Vitoria-Gasteiz","article_modified_time":"2025-02-07T08:48:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/","name":"Ventajas - E.Leclerc Vitoria-Gasteiz","isPartOf":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-1.svg","datePublished":"2024-04-29T19:30:09+00:00","dateModified":"2025-02-07T08:48:29+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/#primaryimage","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-1.svg","contentUrl":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/04\/ventajas-1.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/ventajas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/"},{"@type":"ListItem","position":2,"name":"Tarjeta E.Leclerc","item":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/tarjeta-e-leclerc\/"},{"@type":"ListItem","position":3,"name":"Ventajas"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#website","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/","name":"E.Leclerc Vitoria-Gasteiz","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Vitoria-Gasteiz en Pa\u00eds Vasco. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#organization","name":"E.Leclerc Vitoria-Gasteiz","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/03\/Leclerc_Logo.svg","contentUrl":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-content\/uploads\/sites\/4\/2024\/03\/Leclerc_Logo.svg","caption":"E.Leclerc Vitoria-Gasteiz"},"image":{"@id":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/comments?post=7703"}],"version-history":[{"count":22,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7703\/revisions"}],"predecessor-version":[{"id":8975,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7703\/revisions\/8975"}],"up":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/pages\/7690"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/vitoria-gasteiz\/wp-json\/wp\/v2\/media?parent=7703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}