{"id":8449,"date":"2024-07-04T12:41:30","date_gmt":"2024-07-04T10:41:30","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/\/"},"modified":"2024-07-04T12:41:31","modified_gmt":"2024-07-04T10:41:31","slug":"rebajas-de-verano-en-hipermercado-e-leclerc-soria","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/","title":{"rendered":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"445\" src=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg\" alt=\"\" class=\"wp-image-8450\" style=\"width:700px\" srcset=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg 700w, https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web-300x191.jpg 300w, https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web-520x330.jpg 520w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Del 4 de julio al 4 de Septiembre rebajas en Hipermercado E.Leclerc Soria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCon necesidad de renovar tu fondo de armario?, \u00a1no lo dudes y ac\u00e9rcate del 4 de julio al 4 de septiembre de 2024 a hipermercado E.Leclerc Soria! y disfruta de las <strong>rebajas de verano<\/strong> en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la \u00abEtiqueta Roja\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rebajas de Verano en E.Leclerc Soria, \u00a1No lo dudes y ac\u00e9rcate! <\/p>\n","protected":false},"author":35,"featured_media":8450,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112],"tags":[],"class_list":["post-8449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria<\/title>\n<meta name=\"description\" content=\"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la &quot;Etiqueta Roja&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la &quot;Etiqueta Roja&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T10:41:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T10:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emily\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emily\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/\"},\"author\":{\"name\":\"emily\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/person\\\/32de3111a627cf285893aeb6de2286df\"},\"headline\":\"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA\",\"datePublished\":\"2024-07-04T10:41:30+00:00\",\"dateModified\":\"2024-07-04T10:41:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/Rebajas-Web.jpg\",\"articleSection\":[\"Moda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/\",\"name\":\"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/Rebajas-Web.jpg\",\"datePublished\":\"2024-07-04T10:41:30+00:00\",\"dateModified\":\"2024-07-04T10:41:31+00:00\",\"description\":\"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la \\\"Etiqueta Roja\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/Rebajas-Web.jpg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/Rebajas-Web.jpg\",\"width\":700,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/person\\\/32de3111a627cf285893aeb6de2286df\",\"name\":\"emily\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/author\\\/emily\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria","description":"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la \"Etiqueta Roja\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/","og_locale":"es_ES","og_type":"article","og_title":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria","og_description":"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la \"Etiqueta Roja\".","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2024-07-04T10:41:30+00:00","article_modified_time":"2024-07-04T10:41:31+00:00","og_image":[{"width":700,"height":445,"url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg","type":"image\/jpeg"}],"author":"emily","twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","twitter_misc":{"Escrito por":"emily","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/"},"author":{"name":"emily","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/person\/32de3111a627cf285893aeb6de2286df"},"headline":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA","datePublished":"2024-07-04T10:41:30+00:00","dateModified":"2024-07-04T10:41:31+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/"},"wordCount":69,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg","articleSection":["Moda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/","name":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg","datePublished":"2024-07-04T10:41:30+00:00","dateModified":"2024-07-04T10:41:31+00:00","description":"Del 4 de julio al 4 de septiembre de 2024 ac\u00e9rcate a hipermercado E.Leclerc Soria y disfruta de las rebajas de verano en textil confecci\u00f3n y calzado. Busca los art\u00edculos se\u00f1alados con la \"Etiqueta Roja\".","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#primaryimage","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/06\/Rebajas-Web.jpg","width":700,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/rebajas-de-verano-en-hipermercado-e-leclerc-soria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"REBAJAS DE VERANO EN HIPERMERCADO E.LECLERC SORIA"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]},{"@type":"Person","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/person\/32de3111a627cf285893aeb6de2286df","name":"emily","url":"https:\/\/e-leclerc.es\/soria\/author\/emily\/"}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/8449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=8449"}],"version-history":[{"count":2,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/8449\/revisions"}],"predecessor-version":[{"id":8452,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/8449\/revisions\/8452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media\/8450"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=8449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=8449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=8449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}