{"id":6438,"date":"2016-05-10T11:21:45","date_gmt":"2016-05-10T09:21:45","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/"},"modified":"2016-05-10T11:21:45","modified_gmt":"2016-05-10T09:21:45","slug":"e-leclerc-soria-premio-empresario-del-ano-2015-foes","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/","title":{"rendered":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES"},"content":{"rendered":"<p>Hoy nos hemos despertado con la estupenda noticia de que FOES SORIA nos ha otorgado el premio EMPRESARIO DEL A\u00d1O 2015 Y CECALE DE ORO 2015.<br \/>\nEl premio reconoce los 20 a\u00f1os que H.E.LECLERC Soria lleva apoyando a los proveedores sorianos y creando empleo. \u00abSoriadis S.L., m\u00e1s conocido por su nombre comercial Hipermercado E.Leclerc, con el \u201cPremio FOES Empresario Soriano 2015\u201d y el Premio \u201cCecale de Oro 2015\u201d en reconocimiento a sus 20 a\u00f1os de exitosa andadura empresarial, apostando por nuestra provincia, creando empleo, innovando, potenciando los productos de la tierra e impulsando las relaciones comerciales con proveedores sorianos.<br \/>\nEstamos Felices y encantados con el reconocimiento a 20 a\u00f1os de trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy nos hemos despertado con la estupenda noticia de que FOES SORIA nos ha otorgado el premio EMPRESARIO DEL A\u00d1O 2015 Y CECALE DE ORO 2015. El premio reconoce los 20 a\u00f1os que H.E.LECLERC Soria lleva apoyando a los proveedores sorianos y creando empleo. \u00abSoriadis S.L., m\u00e1s conocido por su nombre comercial Hipermercado E.Leclerc, con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6438","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"Hoy nos hemos despertado con la estupenda noticia de que FOES SORIA nos ha otorgado el premio EMPRESARIO DEL A\u00d1O 2015 Y CECALE DE ORO 2015. El premio reconoce los 20 a\u00f1os que H.E.LECLERC Soria lleva apoyando a los proveedores sorianos y creando empleo. \u00abSoriadis S.L., m\u00e1s conocido por su nombre comercial Hipermercado E.Leclerc, con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T09:21:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES\",\"datePublished\":\"2016-05-10T09:21:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/\",\"name\":\"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"datePublished\":\"2016-05-10T09:21:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/","og_locale":"es_ES","og_type":"article","og_title":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria","og_description":"Hoy nos hemos despertado con la estupenda noticia de que FOES SORIA nos ha otorgado el premio EMPRESARIO DEL A\u00d1O 2015 Y CECALE DE ORO 2015. El premio reconoce los 20 a\u00f1os que H.E.LECLERC Soria lleva apoyando a los proveedores sorianos y creando empleo. \u00abSoriadis S.L., m\u00e1s conocido por su nombre comercial Hipermercado E.Leclerc, con [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2016-05-10T09:21:45+00:00","twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/"},"author":{"name":"","@id":""},"headline":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES","datePublished":"2016-05-10T09:21:45+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/"},"wordCount":122,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/","name":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"datePublished":"2016-05-10T09:21:45+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-soria-premio-empresario-del-ano-2015-foes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"E.LECLERC SORIA PREMIO EMPRESARIO DEL A\u00d1O 2015 FOES"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=6438"}],"version-history":[{"count":0,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6438\/revisions"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=6438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=6438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=6438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}