{"id":6404,"date":"2016-05-10T11:15:17","date_gmt":"2016-05-10T09:15:17","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/"},"modified":"2016-05-10T11:15:17","modified_gmt":"2016-05-10T09:15:17","slug":"h-e-leclerc-colabora-con-bicis-para-la-vida","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/","title":{"rendered":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA"},"content":{"rendered":"<p>Hipermercados E.Leclerc se ha sumado al proyecto \u201cBicis para la Vida\u201d, una iniciativa encabezada por La Fundaci\u00f3n Alberto Contador,y cuyo objetivo es llevar bicicletas a personas en riesgo de exclusi\u00f3n.<\/p>\n<p>Los 18 hipermercados que E.Leclerc tiene en Espa\u00f1a han instalado puntos de recogida de bicicletas usadas donde, todo el que lo desee, podr\u00e1 donar su \u201cbici\u201d y contribuir con este proyecto solidario. Como reconocimiento, cada donante de bicicleta recibir\u00e1 a cambio un vale descuento de 20\u20ac en la compra de su nueva bicicleta en E.Leclerc.<\/p>\n<p>Todas las bicicletas recogidas en los hipermercados E.Leclerc se llevar\u00e1n a un taller que emplea a personas con discapacidad, las cuales se encargar\u00e1n de su reparaci\u00f3n para, posteriormente, ser distribuidas a colectivos con pocos recursos o en riesgo de exclusi\u00f3n, tanto dentro como fuera de Espa\u00f1a.<\/p>\n<p>E.Leclerc se convierte as\u00ed en la primera cadena de hipermercados en sumarse a \u201cBicis para la Vida\u201d: \u201cLa solidaridad y la implicaci\u00f3n en proyectos sociales forman parte de los principios fundamentales de E.Leclerc, y por ello no dudamos en sumarnos a esta iniciativa que, adem\u00e1s de donar bicicletas reparadas a colectivos con pocos recursos, contribuye a la integraci\u00f3n laboral de personas con discapacidad, a las que se da formaci\u00f3n profesional\u201d, se\u00f1alan desde la direcci\u00f3n de E.Leclerc. \u201cAl mismo tiempo, es una manera de fomentar el uso de la bicicleta, como pr\u00e1ctica deportiva o como medio de transporte ecol\u00f3gico\u201d, a\u00f1aden.<\/p>\n<p>Desde E.Leclerc animan a todos a que, \u201csi tienen una bicicleta que ya no utilizan, sea urbana, de monta\u00f1a, infantil\u2026, se acerquen a E.Leclerc y la donen, porque una vez reparada y \u2018puesta a punto\u2019, a\u00fan le queda mucho por recorrer\u201d.<\/p>\n<p>Proyecto Bicis Para la Vida<\/p>\n<p>\u201cBicis para la Vida\u201d es una iniciativa conjunta de Fundaci\u00f3n Alberto Contador, Fundaci\u00f3n SEUR, Asociaci\u00f3n de Minusv\u00e1lidos de Pinto y Fundaci\u00f3n Ananta. El programa gestiona un taller de reparaci\u00f3n de bicicletas que emplea a personas discapacitadas para la posterior distribuci\u00f3n gratuita de las bicicletas a colectivos desfavorecidos. Las bicicletas son recibidas como donaciones y trasladadas a la nave de Pinto por la extensa red de SEUR, con 90 puntos asignados en Espa\u00f1a y Portugal. El taller est\u00e1 gestionado por la Asociaci\u00f3n de Minusv\u00e1lidos de Pinto.<\/p>\n<p>Marcha cicloturista solidaria<\/p>\n<p>Asimismo, E.Leclerc colaborar\u00e1 tambi\u00e9n con la 5\u00aa prueba del Circuito 7 Estrellas MTB, una marcha solidaria a favor de \u201cBicis para la Vida\u201d que tendr\u00e1 lugar el pr\u00f3ximo 15 de noviembre en Pinto (Madrid).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hipermercados E.Leclerc se ha sumado al proyecto \u201cBicis para la Vida\u201d, una iniciativa encabezada por La Fundaci\u00f3n Alberto Contador,y cuyo objetivo es llevar bicicletas a personas en riesgo de exclusi\u00f3n. Los 18 hipermercados que E.Leclerc tiene en Espa\u00f1a han instalado puntos de recogida de bicicletas usadas donde, todo el que lo desee, podr\u00e1 donar su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":6405,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"Hipermercados E.Leclerc se ha sumado al proyecto \u201cBicis para la Vida\u201d, una iniciativa encabezada por La Fundaci\u00f3n Alberto Contador,y cuyo objetivo es llevar bicicletas a personas en riesgo de exclusi\u00f3n. Los 18 hipermercados que E.Leclerc tiene en Espa\u00f1a han instalado puntos de recogida de bicicletas usadas donde, todo el que lo desee, podr\u00e1 donar su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T09:15:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA\",\"datePublished\":\"2016-05-10T09:15:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/\"},\"wordCount\":443,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2fbicis_930.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/\",\"name\":\"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2fbicis_930.jpg\",\"datePublished\":\"2016-05-10T09:15:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2fbicis_930.jpg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2fbicis_930.jpg\",\"width\":620,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/h-e-leclerc-colabora-con-bicis-para-la-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/","og_locale":"es_ES","og_type":"article","og_title":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria","og_description":"Hipermercados E.Leclerc se ha sumado al proyecto \u201cBicis para la Vida\u201d, una iniciativa encabezada por La Fundaci\u00f3n Alberto Contador,y cuyo objetivo es llevar bicicletas a personas en riesgo de exclusi\u00f3n. Los 18 hipermercados que E.Leclerc tiene en Espa\u00f1a han instalado puntos de recogida de bicicletas usadas donde, todo el que lo desee, podr\u00e1 donar su [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2016-05-10T09:15:17+00:00","og_image":[{"width":620,"height":360,"url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/"},"author":{"name":"","@id":""},"headline":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA","datePublished":"2016-05-10T09:15:17+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/"},"wordCount":443,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/","name":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg","datePublished":"2016-05-10T09:15:17+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#primaryimage","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2fbicis_930.jpg","width":620,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/h-e-leclerc-colabora-con-bicis-para-la-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"H.E.LECLERC COLABORA CON BICIS PARA LA VIDA"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=6404"}],"version-history":[{"count":0,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media\/6405"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=6404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=6404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=6404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}