{"id":6400,"date":"2016-05-10T11:12:29","date_gmt":"2016-05-10T09:12:29","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/"},"modified":"2016-05-10T11:12:29","modified_gmt":"2016-05-10T09:12:29","slug":"e-leclerc-colabora-en-las-actividades-de-san-saturio-2014","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/","title":{"rendered":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014"},"content":{"rendered":"<p>H.E.Leclerc se vuelca un a\u00f1o mas con las actividades que tiene lugar entorno a las fiestas de San Saturio 2014.<br \/>\nUna vez mas ha colaborado con la Asociaci\u00f3n de Encajeras Leonor que ha celebrado el VIII Encuentro de Encajeras aportando regalos para sortear entre las participantes.<br \/>\nAsimismo colabora con el C.D Alto Real en el XIV Campeonato de Tiro con Arco el d\u00eda 05\/10\/14.<br \/>\nTambi\u00e9n se ha colaborado con el C.D Ciclista Calaveron en su LIV Trofeo San Saturio y con el Club de Boxeo en su velada nocturna del d\u00eda 10\/10\/14.<br \/>\nE.Leclerc quiere estar presente en al vida social y cultural de la ciudad y se compromete con ello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H.E.Leclerc se vuelca un a\u00f1o mas con las actividades que tiene lugar entorno a las fiestas de San Saturio 2014. Una vez mas ha colaborado con la Asociaci\u00f3n de Encajeras Leonor que ha celebrado el VIII Encuentro de Encajeras aportando regalos para sortear entre las participantes. Asimismo colabora con el C.D Alto Real en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":6401,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"H.E.Leclerc se vuelca un a\u00f1o mas con las actividades que tiene lugar entorno a las fiestas de San Saturio 2014. Una vez mas ha colaborado con la Asociaci\u00f3n de Encajeras Leonor que ha celebrado el VIII Encuentro de Encajeras aportando regalos para sortear entre las participantes. Asimismo colabora con el C.D Alto Real en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T09:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014\",\"datePublished\":\"2016-05-10T09:12:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2bsaturio_882.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/\",\"name\":\"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2bsaturio_882.jpg\",\"datePublished\":\"2016-05-10T09:12:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2bsaturio_882.jpg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2bsaturio_882.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/","og_locale":"es_ES","og_type":"article","og_title":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria","og_description":"H.E.Leclerc se vuelca un a\u00f1o mas con las actividades que tiene lugar entorno a las fiestas de San Saturio 2014. Una vez mas ha colaborado con la Asociaci\u00f3n de Encajeras Leonor que ha celebrado el VIII Encuentro de Encajeras aportando regalos para sortear entre las participantes. Asimismo colabora con el C.D Alto Real en el [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2016-05-10T09:12:29+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/"},"author":{"name":"","@id":""},"headline":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014","datePublished":"2016-05-10T09:12:29+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/"},"wordCount":126,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/","name":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014 - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg","datePublished":"2016-05-10T09:12:29+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#primaryimage","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2bsaturio_882.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/e-leclerc-colabora-en-las-actividades-de-san-saturio-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"E.LECLERC COLABORA EN LAS ACTIVIDADES DE SAN SATURIO 2014"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=6400"}],"version-history":[{"count":0,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media\/6401"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=6400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=6400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=6400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}