{"id":6384,"date":"2016-05-10T11:11:26","date_gmt":"2016-05-10T09:11:26","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/"},"modified":"2016-05-10T11:11:26","modified_gmt":"2016-05-10T09:11:26","slug":"cumplimos-18-anos-juntos","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/","title":{"rendered":"CUMPLIMOS 18 A\u00d1OS JUNTOS"},"content":{"rendered":"<p>Hace 18 a\u00f1os comenzamos nuestra andadura como Hipermercado.<br \/>\nMuchos de nosotros \u00e9ramos j\u00f3venes que empez\u00e1bamos en nuestros primeros trabajos y aqu\u00ed nos hemos ido formando como profesionales y como personas. La mayor parte de los trabajadores somos sorianos y los que no, hace tiempo que se sienten de Soria.<br \/>\nEn estos 18 a\u00f1os nos hemos convertido en una familia, algunos se han ido y otros han vuelto. Hemos visto pasar a muchos sorianos y forasteros por nuestros mostradores y cajas y siempre hemos intentado ser innovadores y dar el mejor surtido y atenci\u00f3n posible.<br \/>\nCumplimos nuestra mayor\u00eda de edad como Hipermercado y en el trayecto hemos  mejorado nuestras instalaciones a\u00f1adiendo:<br \/>\nUna gasolinera que actualmente se encuentra en proceso de renovaci\u00f3n,<br \/>\nUn supermercado en el centro para estar m\u00e1s cerca de la gente y de los barrios.<br \/>\nHemos renovado nuestra cafeter\u00eda Bamb\u00fa convirti\u00e9ndola en uno de los mejores restaurantes relaci\u00f3n calidad-precio de Soria.<br \/>\nHemos ampliado servicios al cliente con la tintorer\u00eda y La Vinoteca, y todo sin perder la ilusi\u00f3n y las ganas con las que empezamos hace 18 a\u00f1os.<br \/>\nSiempre enfocados en hacer que nuestra ciudad mejore, que nuestras empresas tengan un buen escaparate donde ofrecer sus productos, Apoyando el producto Soriano.<br \/>\nFormamos parte de la vida deportiva y social de la ciudad colaborando con clubes y asociaciones de todas las \u00edndoles.<br \/>\nEsperamos seguir as\u00ed al menos otros 18 a\u00f1os m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 18 a\u00f1os comenzamos nuestra andadura como Hipermercado. Muchos de nosotros \u00e9ramos j\u00f3venes que empez\u00e1bamos en nuestros primeros trabajos y aqu\u00ed nos hemos ido formando como profesionales y como personas. La mayor parte de los trabajadores somos sorianos y los que no, hace tiempo que se sienten de Soria. En estos 18 a\u00f1os nos hemos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":6385,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"Hace 18 a\u00f1os comenzamos nuestra andadura como Hipermercado. Muchos de nosotros \u00e9ramos j\u00f3venes que empez\u00e1bamos en nuestros primeros trabajos y aqu\u00ed nos hemos ido formando como profesionales y como personas. La mayor parte de los trabajadores somos sorianos y los que no, hace tiempo que se sienten de Soria. En estos 18 a\u00f1os nos hemos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T09:11:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CUMPLIMOS 18 A\u00d1OS JUNTOS\",\"datePublished\":\"2016-05-10T09:11:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/\"},\"wordCount\":248,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2faniv4_853.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/\",\"name\":\"CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2faniv4_853.jpg\",\"datePublished\":\"2016-05-10T09:11:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2faniv4_853.jpg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/2faniv4_853.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/cumplimos-18-anos-juntos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUMPLIMOS 18 A\u00d1OS JUNTOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/","og_locale":"es_ES","og_type":"article","og_title":"CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria","og_description":"Hace 18 a\u00f1os comenzamos nuestra andadura como Hipermercado. Muchos de nosotros \u00e9ramos j\u00f3venes que empez\u00e1bamos en nuestros primeros trabajos y aqu\u00ed nos hemos ido formando como profesionales y como personas. La mayor parte de los trabajadores somos sorianos y los que no, hace tiempo que se sienten de Soria. En estos 18 a\u00f1os nos hemos [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2016-05-10T09:11:26+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/"},"author":{"name":"","@id":""},"headline":"CUMPLIMOS 18 A\u00d1OS JUNTOS","datePublished":"2016-05-10T09:11:26+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/"},"wordCount":248,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/","name":"CUMPLIMOS 18 A\u00d1OS JUNTOS - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg","datePublished":"2016-05-10T09:11:26+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#primaryimage","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/2faniv4_853.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/cumplimos-18-anos-juntos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"CUMPLIMOS 18 A\u00d1OS JUNTOS"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=6384"}],"version-history":[{"count":0,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media\/6385"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=6384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=6384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=6384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}