{"id":6358,"date":"2016-05-10T11:07:34","date_gmt":"2016-05-10T09:07:34","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/"},"modified":"2016-05-10T11:07:34","modified_gmt":"2016-05-10T09:07:34","slug":"16-aniversario-e-leclerc-soria","status":"publish","type":"post","link":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/","title":{"rendered":"16 ANIVERSARIO E.LECLERC SORIA"},"content":{"rendered":"<p>E.Leclerc celebra su 16 aniversario con un mont\u00f3n de regalos, ven y participa en nuestra t\u00f3mbola!!<br \/>\nUn a\u00f1o mas, y ya son 16, E.Leclerc Soria quiere celebrar su aniversario con todos su clientes, sorteando 3 premios de 2500 euros ademas de un gran numero de regalos en su tombola.<br \/>\nAdemas entre todos los clientes sortearan 3 premios de 2500\u20ac.<br \/>\nven y celebralo con nosotros!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E.Leclerc celebra su 16 aniversario con un mont\u00f3n de regalos, ven y participa en nuestra t\u00f3mbola!! Un a\u00f1o mas, y ya son 16, E.Leclerc Soria quiere celebrar su aniversario con todos su clientes, sorteando 3 premios de 2500 euros ademas de un gran numero de regalos en su tombola. Ademas entre todos los clientes sortearan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":6359,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"E.Leclerc celebra su 16 aniversario con un mont\u00f3n de regalos, ven y participa en nuestra t\u00f3mbola!! Un a\u00f1o mas, y ya son 16, E.Leclerc Soria quiere celebrar su aniversario con todos su clientes, sorteando 3 premios de 2500 euros ademas de un gran numero de regalos en su tombola. Ademas entre todos los clientes sortearan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T09:07:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"16 ANIVERSARIO E.LECLERC SORIA\",\"datePublished\":\"2016-05-10T09:07:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/aniversario_753.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/\",\"name\":\"16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/aniversario_753.jpg\",\"datePublished\":\"2016-05-10T09:07:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/aniversario_753.jpg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/05\\\/aniversario_753.jpg\",\"width\":225,\"height\":268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/tendencias\\\/16-aniversario-e-leclerc-soria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"16 ANIVERSARIO E.LECLERC SORIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/","og_locale":"es_ES","og_type":"article","og_title":"16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria","og_description":"E.Leclerc celebra su 16 aniversario con un mont\u00f3n de regalos, ven y participa en nuestra t\u00f3mbola!! Un a\u00f1o mas, y ya son 16, E.Leclerc Soria quiere celebrar su aniversario con todos su clientes, sorteando 3 premios de 2500 euros ademas de un gran numero de regalos en su tombola. Ademas entre todos los clientes sortearan [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_published_time":"2016-05-10T09:07:34+00:00","og_image":[{"width":225,"height":268,"url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@LeclercSoria","twitter_site":"@LeclercSoria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#article","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/"},"author":{"name":"","@id":""},"headline":"16 ANIVERSARIO E.LECLERC SORIA","datePublished":"2016-05-10T09:07:34+00:00","mainEntityOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/"},"wordCount":67,"publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/","url":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/","name":"16 ANIVERSARIO E.LECLERC SORIA - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg","datePublished":"2016-05-10T09:07:34+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#primaryimage","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2016\/05\/aniversario_753.jpg","width":225,"height":268},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/tendencias\/16-aniversario-e-leclerc-soria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"16 ANIVERSARIO E.LECLERC SORIA"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=6358"}],"version-history":[{"count":0,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/posts\/6358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media\/6359"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=6358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/categories?post=6358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/tags?post=6358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}