{"id":11866,"date":"2025-06-20T21:25:25","date_gmt":"2025-06-20T19:25:25","guid":{"rendered":"https:\/\/www.e-leclerc.es\/soria\/?page_id=11866"},"modified":"2025-06-20T21:25:26","modified_gmt":"2025-06-20T19:25:26","slug":"bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria","status":"publish","type":"page","link":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/","title":{"rendered":"Bases de participaci\u00f3n \u00abSorteo Tour de Francia 2025\u00bb E.Leclerc Soria"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>1.- Organizador:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La sociedad SORIADIS S.L. sita en Pol\u00edgono Industrial Las Casas C\/J Parc.290 42005 Soria, y CIF B42141176, explotadora del hipermercado y supermercado\/s E.Leclerc Soria (en adelante \u201cE.Leclerc\u201d), tiene previsto organizar una promoci\u00f3n dirigida a sus clientes, en el \u00e1mbito territorial de su ubicaci\u00f3n (Soria), que se llevar\u00e1 a cabo en el lugar, fechas y condiciones que m\u00e1s adelante se detallan.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2.- Objetivo y plazo de participaci\u00f3n:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de esta promoci\u00f3n es premiar la fidelidad de los clientes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta promoci\u00f3n \u00fanicamente participar\u00e1n aquellas personas que realicen una compra por <strong>importe m\u00ednimo superior de 50 euros en el hipermercado, vinoteca, parafarmacia y tintorer\u00eda o superior a 20\u20ac en los supermercados E.Leclerc de Soria,&nbsp; <\/strong><em>(excepto las que se hagan en&nbsp; gasolinera, lavadero, cafeter\u00eda y compra Online) <\/em><strong>desde el d\u00eda 01 de julio de 2025 hasta el 02 de agosto de 2025<\/strong>, siempre y cuando los establecimientos est\u00e9n abiertos al p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3.- Legitimaci\u00f3n para participar:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1n participar en esta promoci\u00f3n y resultar ganadores de la misma, todas aquellas personas f\u00edsicas, mayores de edad, y con residencia fiscal en el territorio nacional de Espa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los empleados de los hipermercados y supermercados de Soria, Personal de Seguridad del centro, personal de ISS y personal de OPV, podr\u00e1n participar en el sorteo de los productos promocionales del Tour de Francia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No podr\u00e1n participar en el sorteo ni resultar ganadores del mismo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aquellas personas que en el momento de realizarse esta promoci\u00f3n sean deudoras por cualquier t\u00edtulo de los hipermercados o supermercados E.Leclerc por cualquier cantidad vencida y no pagada.\u00a0<\/li>\n\n\n\n<li>Las personas jur\u00eddicas.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de que alguna de estas personas participe en la promoci\u00f3n y resulte ganadora, en ning\u00fan caso se le otorgar\u00e1 el premio correspondiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cualquier participaci\u00f3n obtenida de manera anormal, en violaci\u00f3n de estas bases o por medio de manipulaciones t\u00e9cnicas destinadas a falsear su honradez, intrusi\u00f3n, o tentativa de intrusi\u00f3n, ser\u00e1 cancelada reserv\u00e1ndose E.Leclerc el derecho de perseguir al autor del fraude.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4.- Mec\u00e1nica de la promoci\u00f3n:&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para participar en esta promoci\u00f3n, los clientes deben realizar una compra con importe m\u00ednimo superior de 50 euros en el hipermercado, vinoteca, parafarmacia y tintorer\u00eda o superior a 20\u20ac en los supermercados E.Leclerc de Soria <em>(excepto las que se hagan en&nbsp; gasolinera, lavadero, cafeter\u00eda y compra Online).<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La mec\u00e1nica ser\u00e1:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tour Masculino+Femenino: Periodo del 01 de julio al 2 de agosto de 2025:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tras el ticket de caja por importe m\u00ednimo superior a 50 euros en el hipermercado, vinoteca, parafarmacia y tintorer\u00eda o superior a 20 euros en los supermercados un programa inform\u00e1tico determinar\u00e1 aleatoriamente si el cliente ha sido agraciado con un premio o no. El premio consiste en: <strong>camisetas o llaveros peluche o llaveros camiseta o bolsa compra o palas playa o mantel picnic o pack bolsa o pack mochila o gafas de sol promocionales del tour de Francia<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos premiados con camisetas o llaveros peluche o llaveros camiseta o bolsa compra o palas playa o mantel picnic o pack bolsa o pack mochila o gafas de sol promocionales del tour de Francia, se canjear\u00e1n por el premio correspondiente en informaci\u00f3n de E.Leclerc Soria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos no se emitir\u00e1n en las cajas de Gasolinera, lavadero, Cafeter\u00eda, ni Compra Online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos de la promoci\u00f3n fotocopiados no ser\u00e1n aceptados ni considerados v\u00e1lidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5.- Premios:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos premiados con camisetas o llaveros peluche o llaveros camiseta o bolsa compra o palas playa o mantel picnic o pack bolsa o pack mochila o gafas de sol promocionales del tour de Francia, se canjear\u00e1n por el premio correspondiente en informaci\u00f3n de E.Leclerc Soria. Queda prohibido su canje por dinero o cualquier otro premio distinto al descrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos premiados caducan a las 21:30 del 02 de agosto de 2025, pasada esta fecha perder\u00e1n toda efectividad, consider\u00e1ndose caducados a todos los efectos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>6.- Entrega de los premios.&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los premios se recoger\u00e1n, en los puntos de informaci\u00f3n del hipermercado y supermercados E.Leclerc Soria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos de la promoci\u00f3n fotocopiados no ser\u00e1n aceptados ni considerados v\u00e1lidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>7.- Renuncia o imposibilidad de aceptaci\u00f3n:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de que por cualquier circunstancia el premiado renunciar\u00e1 o por cualquier raz\u00f3n no pudiera aceptar el premio correspondiente, Soriadis, S.L. no proceder\u00e1 a realizar ning\u00fan canje por dinero ni por cualquier otro premio distinto al descrito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>8.- Per\u00edodo de reclamaci\u00f3n:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El per\u00edodo para interponer cualquier reclamaci\u00f3n por quien tenga derecho a ella, relativa a la celebraci\u00f3n de la promoci\u00f3n finalizar\u00e1 transcurridos 14 d\u00edas naturales desde la fecha de celebraci\u00f3n del sorteo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>9.- Fiscalidad de los premios:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Soriadis, S.L.realizar\u00e1 sobre el premio, la retenci\u00f3n o ingreso a cuenta que de acuerdo con la normativa fiscal en vigor sea aplicable en el momento de su entrega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ingreso de dicha retenci\u00f3n en la Agencia Tributaria correr\u00e1 a cargo de Soriadis, S.L. En cualquier caso, esta sociedad emitir\u00e1 en su momento al ganador, a los efectos de su declaraci\u00f3n de IRPF, el correspondiente certificado de retenciones e ingresos a cuenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ganador del premio deber\u00e1 integrar en su base imponible de la declaraci\u00f3n del IRPF del correspondiente ejercicio fiscal, la valoraci\u00f3n del premio m\u00e1s el ingreso a cuenta que la sociedad explotadora del hipermercado E.Leclerc Soria realiz\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>10.- Legislaci\u00f3n y jurisdicci\u00f3n aplicable:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estos t\u00e9rminos y condiciones se regir\u00e1n por las leyes del Estado espa\u00f1ol, y las partes aceptan someterse a la jurisdicci\u00f3n exclusiva de los tribunales espa\u00f1oles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>11.- Protecci\u00f3n de datos personales:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La recogida y el tratamiento de los datos se realizar\u00e1 de conformidad con las exigencias del Reglamento (UE) 2016\/679 relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (en adelante, el \u201cReglamento General de Protecci\u00f3n de Datos\u201d o \u201cRGPD\u201d)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Responsable del tratamiento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">E.Leclerc Soria informa a los clientes que los datos personales que se les solicitan en el boleto de participaci\u00f3n, y que libre y voluntariamente facilitan, ser\u00e1n recogidos y tratados por Soriadis, S.L. e incluidos en un fichero de su responsabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soriadis, S.L. se compromete a tratar los datos personales con total confidencialidad y respetando las t\u00e9cnicas y organizativas apropiadas a fin de garantizar y poder demostrar que el tratamiento es conforme con el RGPD.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Finalidad del tratamiento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos recabados por el Responsable se tratar\u00e1n con la finalidad principal de gestionar su participaci\u00f3n en la promoci\u00f3n; una vez realizada, y pasado el plazo de reclamaciones y de entrega de los premios, los datos ser\u00e1n eliminados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para cualquier otra finalidad en el uso y tratamiento de los datos personales del participante distinta de la participaci\u00f3n en la promoci\u00f3n, se le informar\u00e1 expresamente y deber\u00e1, si as\u00ed lo desea, dar su consentimiento individualizado y afirmativo a tal fin, al rellenar el boleto de participaci\u00f3n. Del mismo modo, se le informar\u00e1 expresamente de si la aceptaci\u00f3n de otras finalidades fuera necesaria para llevar a cabo la finalidad principal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Legitimaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La base legal para el tratamiento de los datos del participante se fundamenta en el consentimiento que se le solicita mediante la aceptaci\u00f3n de estas bases y con la firma del boleto de participaci\u00f3n, consintiendo expresamente el tratamiento de sus datos personales por parte del Responsables del Tratamiento correspondiente a SORIADIS, S.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el supuesto de que no se suministren todos los datos de respuesta obligatoria se podr\u00e1 proceder al bloqueo de la participaci\u00f3n hasta la inclusi\u00f3n de los mismos. Los datos considerados como obligatorios ser\u00e1n los estrictamente necesarios para la finalidad del tratamiento anteriormente indicada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Destinatarios<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los Responsables del tratamiento no ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Exactitud de los datos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En cumplimiento del principio de calidad de los datos personales, expresado en el art\u00edculo 5 d) del RGPD, el participante se compromete a facilitar datos verdaderos, exactos, completos y actualizados, de forma que respondan con veracidad a la situaci\u00f3n de \u00e9ste siendo el \u00fanico responsable en caso de ser falsos, incompletos, no actualizados o inexactos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Derechos del cliente<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes pueden ejercitar sus derechos de acceso a sus datos personales, rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines que fueron recogidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes podr\u00e1n solicitar la limitaci\u00f3n u oposici\u00f3n al tratamiento de sus datos, en cuyo caso dejar\u00e1n de utilizarse salvo que su conservaci\u00f3n sea necesaria para el ejercicio o la defensa de reclamaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes podr\u00e1n en todo caso solicitar el derecho a la portabilidad de sus datos, recibiendo del Responsable los datos personales que le incumban y le hubiese facilitado, en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y pudiendo transmitirlos a otro responsable del tratamiento sin que lo impida el Responsable al que se los hubiera facilitado. Este derecho podr\u00e1 ejercerse siempre que el cliente no hubiese ejercido anteriormente su derecho de supresi\u00f3n o los datos hubiesen sido cancelados por el Responsable al terminar la finalidad principal por la que fueron recabados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cliente tendr\u00e1 derecho a retirar el consentimiento otorgado para cualquier finalidad en cualquier momento, sin que dicha retirada afecte a la licitud del tratamiento basada en el consentimiento previo a su retirada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos estos derechos podr\u00e1 ejercitarlos de forma gratuita dirigi\u00e9ndose al Responsable del tratamiento del hipermercado donde deposit\u00f3 el boleto, deber\u00e1 realizar una solicitud escrita a nuestra direcci\u00f3n o correo electr\u00f3nico, junto con una fotocopia de su DNI, para poder identificarle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n postal:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soriadis, S.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pol. Ind. Las Casas Calle J parcela 290<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">42005 Soria<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n postal:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">dpd@audidat.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debiendo incluir el cliente en la comunicaci\u00f3n sus datos personales para poder tramitar el derecho exigido en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Responsable del tratamiento facilitar\u00e1 al interesado informaci\u00f3n relativa a sus actuaciones sobre la base de una solicitud de ejercicio de derechos y, en cualquier caso, en el plazo de un mes a partir de la recepci\u00f3n de la solicitud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho plazo podr\u00e1 prorrogarse otros dos meses en caso necesario, teniendo en cuenta la complejidad y el n\u00famero de solicitudes. El responsable informar\u00e1 al interesado de cualquiera de dichas pr\u00f3rrogas en el plazo de un mes a partir de la recepci\u00f3n de la solicitud, indicando los motivos de la dilaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el interesado presente la solicitud por medios electr\u00f3nicos, la informaci\u00f3n se facilitar\u00e1 por medios electr\u00f3nicos cuando sea posible, a menos que el interesado solicite que se facilite de otro modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el responsable del tratamiento no da curso a la solicitud del interesado, le informar\u00e1 sin dilaci\u00f3n, y a m\u00e1s tardar transcurrido un mes de la recepci\u00f3n de la solicitud, de las razones de su no actuaci\u00f3n y de la posibilidad de presentar en todo caso una reclamaci\u00f3n ante una autoridad de control y de ejercitar acciones judiciales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En caso de que entienda que sus derechos han sido desatendidos, \u00bfd\u00f3nde puede formular una reclamaci\u00f3n?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de que entienda que sus derechos han sido desatendidos por nuestra entidad, puede formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, a trav\u00e9s de alguno de los medios siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sede electr\u00f3nica: <strong>www.agpd.es<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n postal:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agencia Espa\u00f1ola de Protecci\u00f3n de Datos<br>C\/ Jorge Juan, 6<br>28001-Madrid&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00eda telef\u00f3nica:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Telf. 901 100 099&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Telf. 91 266 35 17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos no conlleva ning\u00fan coste y no es necesaria la asistencia de abogado ni procurador.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>ANEXO I<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Reparto de premios.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>PREMIOS DIRECTOS TOUR MASCULINO y FEMENINO<\/strong><strong>Del 01\/07 al 02\/08<\/strong><\/td><td><\/td><\/tr><tr><td><strong>Por importe m\u00ednimo de compra 50\u20ac en el Hipermercado, vinoteca, parafarmacia y tintorer\u00eda,<\/strong><strong>o m\u00ednimo de compra de 20\u20ac en los supermercados.&nbsp;<\/strong><\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>Camisetas<\/strong><\/td><td><strong>359<\/strong><\/td><\/tr><tr><td><strong>Llaveros Peluche<\/strong><\/td><td><strong>300<\/strong><\/td><\/tr><tr><td><strong>Llaveros Camiseta<\/strong><\/td><td><strong>350<\/strong><\/td><\/tr><tr><td><strong>Bolsas Compra<\/strong><\/td><td><strong>200<\/strong><\/td><\/tr><tr><td><strong>Gorras<\/strong><\/td><td><strong>2<\/strong><\/td><\/tr><tr><td><strong>Mantel Picnic<\/strong><\/td><td><strong>1<\/strong><\/td><\/tr><tr><td><strong>Palas de playa<\/strong><\/td><td><strong>1<\/strong><\/td><\/tr><tr><td><strong>Pack Bolsa: Bolsa, camiseta, pa\u00f1uelo, gorra<\/strong><\/td><td><strong>1<\/strong><\/td><\/tr><tr><td><strong>Pack mochila: Mochila, camiseta, pa\u00f1uelo, gorra<\/strong><\/td><td><strong>1<\/strong><\/td><\/tr><tr><td><strong>Gafas de Sol<\/strong><\/td><td><strong>1<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>1.- Organizador: La sociedad SORIADIS S.L. sita en Pol\u00edgono Industrial Las Casas C\/J Parc.290 42005 Soria, y CIF B42141176, explotadora del hipermercado y supermercado\/s E.Leclerc Soria (en adelante \u201cE.Leclerc\u201d), tiene previsto organizar una promoci\u00f3n dirigida a sus clientes, en el \u00e1mbito territorial de su ubicaci\u00f3n (Soria), que se llevar\u00e1 a cabo en el lugar, fechas [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11866","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bases de participaci\u00f3n &quot;Sorteo Tour de Francia 2025&quot; E.Leclerc Soria - E.Leclerc Soria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bases de participaci\u00f3n &quot;Sorteo Tour de Francia 2025&quot; E.Leclerc Soria - E.Leclerc Soria\" \/>\n<meta property=\"og:description\" content=\"1.- Organizador: La sociedad SORIADIS S.L. sita en Pol\u00edgono Industrial Las Casas C\/J Parc.290 42005 Soria, y CIF B42141176, explotadora del hipermercado y supermercado\/s E.Leclerc Soria (en adelante \u201cE.Leclerc\u201d), tiene previsto organizar una promoci\u00f3n dirigida a sus clientes, en el \u00e1mbito territorial de su ubicaci\u00f3n (Soria), que se llevar\u00e1 a cabo en el lugar, fechas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Soria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eleclercsoria?ref=hl\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T19:25:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LeclercSoria\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\\\/\",\"name\":\"Bases de participaci\u00f3n \\\"Sorteo Tour de Francia 2025\\\" E.Leclerc Soria - E.Leclerc Soria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\"},\"datePublished\":\"2025-06-20T19:25:25+00:00\",\"dateModified\":\"2025-06-20T19:25:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bases de participaci\u00f3n \u00abSorteo Tour de Francia 2025\u00bb E.Leclerc Soria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"name\":\"E.Leclerc Soria\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\"},\"alternateName\":\"E.Leclerc Soria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#organization\",\"name\":\"E.Leclerc Soria\",\"alternateName\":\"Soriadis, S.L.\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Logo_Soria-1.svg\",\"width\":100,\"height\":100,\"caption\":\"E.Leclerc Soria\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/soria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eleclercsoria?ref=hl\",\"https:\\\/\\\/x.com\\\/LeclercSoria\",\"https:\\\/\\\/www.instagram.com\\\/e.leclercsoria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bases de participaci\u00f3n \"Sorteo Tour de Francia 2025\" E.Leclerc Soria - E.Leclerc Soria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/","og_locale":"es_ES","og_type":"article","og_title":"Bases de participaci\u00f3n \"Sorteo Tour de Francia 2025\" E.Leclerc Soria - E.Leclerc Soria","og_description":"1.- Organizador: La sociedad SORIADIS S.L. sita en Pol\u00edgono Industrial Las Casas C\/J Parc.290 42005 Soria, y CIF B42141176, explotadora del hipermercado y supermercado\/s E.Leclerc Soria (en adelante \u201cE.Leclerc\u201d), tiene previsto organizar una promoci\u00f3n dirigida a sus clientes, en el \u00e1mbito territorial de su ubicaci\u00f3n (Soria), que se llevar\u00e1 a cabo en el lugar, fechas [&hellip;]","og_url":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/","og_site_name":"E.Leclerc Soria","article_publisher":"https:\/\/www.facebook.com\/eleclercsoria?ref=hl","article_modified_time":"2025-06-20T19:25:26+00:00","twitter_card":"summary_large_image","twitter_site":"@LeclercSoria","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/","url":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/","name":"Bases de participaci\u00f3n \"Sorteo Tour de Francia 2025\" E.Leclerc Soria - E.Leclerc Soria","isPartOf":{"@id":"https:\/\/e-leclerc.es\/soria\/#website"},"datePublished":"2025-06-20T19:25:25+00:00","dateModified":"2025-06-20T19:25:26+00:00","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/soria\/bases-de-participacion-sorteo-tour-de-francia-2025-e-leclerc-soria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/soria\/"},{"@type":"ListItem","position":2,"name":"Bases de participaci\u00f3n \u00abSorteo Tour de Francia 2025\u00bb E.Leclerc Soria"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/soria\/#website","url":"https:\/\/e-leclerc.es\/soria\/","name":"E.Leclerc Soria","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Soria en Castilla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/soria\/#organization"},"alternateName":"E.Leclerc Soria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/soria\/#organization","name":"E.Leclerc Soria","alternateName":"Soriadis, S.L.","url":"https:\/\/e-leclerc.es\/soria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","contentUrl":"https:\/\/e-leclerc.es\/soria\/wp-content\/uploads\/sites\/3\/2024\/05\/Logo_Soria-1.svg","width":100,"height":100,"caption":"E.Leclerc Soria"},"image":{"@id":"https:\/\/e-leclerc.es\/soria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eleclercsoria?ref=hl","https:\/\/x.com\/LeclercSoria","https:\/\/www.instagram.com\/e.leclercsoria\/"]}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/pages\/11866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/comments?post=11866"}],"version-history":[{"count":1,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/pages\/11866\/revisions"}],"predecessor-version":[{"id":11867,"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/pages\/11866\/revisions\/11867"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/soria\/wp-json\/wp\/v2\/media?parent=11866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}