{"id":4859,"date":"2024-04-24T18:59:18","date_gmt":"2024-04-24T16:59:18","guid":{"rendered":"https:\/\/www.e-leclerc.es\/salamanca\/?post_type=gasolinera&#038;p=4859"},"modified":"2026-09-02T08:32:52","modified_gmt":"2026-09-02T06:32:52","slug":"gasolinera-e-leclerc-salamanca","status":"publish","type":"gasolinera","link":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/","title":{"rendered":"Gasolinera E. Leclerc Salamanca"},"content":{"rendered":"","protected":false},"featured_media":6873,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4859","gasolinera","type-gasolinera","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca<\/title>\n<meta name=\"description\" content=\"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca\" \/>\n<meta property=\"og:description\" content=\"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/\" \/>\n<meta property=\"og:site_name\" content=\"E.Leclerc Salamanca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T06:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/04\/Gasolinera-salamanca.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/\",\"name\":\"Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/04\\\/Gasolinera-salamanca.jpeg\",\"datePublished\":\"2024-04-24T16:59:18+00:00\",\"dateModified\":\"2026-09-02T06:32:52+00:00\",\"description\":\"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/04\\\/Gasolinera-salamanca.jpeg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/04\\\/Gasolinera-salamanca.jpeg\",\"width\":1100,\"height\":632},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/gasolinera\\\/gasolinera-e-leclerc-salamanca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gasolinera E. Leclerc Salamanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#website\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/\",\"name\":\"E.Leclerc Salamanca\",\"description\":\"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Salamanca en Castillla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#organization\",\"name\":\"E.Leclerc Salamanca\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/03\\\/Leclerc_Logo.svg\",\"caption\":\"E.Leclerc Salamanca\"},\"image\":{\"@id\":\"https:\\\/\\\/e-leclerc.es\\\/salamanca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca","description":"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/","og_locale":"es_ES","og_type":"article","og_title":"Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca","og_description":"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.","og_url":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/","og_site_name":"E.Leclerc Salamanca","article_modified_time":"2026-09-02T06:32:52+00:00","og_image":[{"width":1100,"height":632,"url":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/04\/Gasolinera-salamanca.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/","url":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/","name":"Gasolinera E. Leclerc Salamanca - E.Leclerc Salamanca","isPartOf":{"@id":"https:\/\/e-leclerc.es\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/#primaryimage"},"image":{"@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/#primaryimage"},"thumbnailUrl":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/04\/Gasolinera-salamanca.jpeg","datePublished":"2024-04-24T16:59:18+00:00","dateModified":"2026-09-02T06:32:52+00:00","description":"Nuestros carburantes contienen los mejores aditivos existentes en el mercado. La m\u00e1s alta calidad asegurada al mejor precio.","breadcrumb":{"@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/#primaryimage","url":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/04\/Gasolinera-salamanca.jpeg","contentUrl":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/04\/Gasolinera-salamanca.jpeg","width":1100,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/e-leclerc.es\/salamanca\/gasolinera\/gasolinera-e-leclerc-salamanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/e-leclerc.es\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Gasolinera E. Leclerc Salamanca"}]},{"@type":"WebSite","@id":"https:\/\/e-leclerc.es\/salamanca\/#website","url":"https:\/\/e-leclerc.es\/salamanca\/","name":"E.Leclerc Salamanca","description":"Descubre los folletos, ofertas y promociones de nuestro hipermercado E.Leclerc Salamanca en Castillla y Le\u00f3n. Direcci\u00f3n | Horario | Productos locales","publisher":{"@id":"https:\/\/e-leclerc.es\/salamanca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-leclerc.es\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/e-leclerc.es\/salamanca\/#organization","name":"E.Leclerc Salamanca","url":"https:\/\/e-leclerc.es\/salamanca\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/e-leclerc.es\/salamanca\/#\/schema\/logo\/image\/","url":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/03\/Leclerc_Logo.svg","contentUrl":"https:\/\/e-leclerc.es\/salamanca\/wp-content\/uploads\/sites\/17\/2024\/03\/Leclerc_Logo.svg","caption":"E.Leclerc Salamanca"},"image":{"@id":"https:\/\/e-leclerc.es\/salamanca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/gasolinera\/4859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/gasolinera"}],"about":[{"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/types\/gasolinera"}],"version-history":[{"count":412,"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/gasolinera\/4859\/revisions"}],"predecessor-version":[{"id":10928,"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/gasolinera\/4859\/revisions\/10928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/media\/6873"}],"wp:attachment":[{"href":"https:\/\/e-leclerc.es\/salamanca\/wp-json\/wp\/v2\/media?parent=4859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}